{"id":2771,"date":"2020-01-27T12:30:00","date_gmt":"2020-01-27T17:30:00","guid":{"rendered":"https:\/\/the-laurent-lab.com\/?p=2771"},"modified":"2021-02-01T12:32:47","modified_gmt":"2021-02-01T17:32:47","slug":"ines-est-de-retour","status":"publish","type":"post","link":"https:\/\/the-laurent-lab.com\/fr\/ines-est-de-retour\/","title":{"rendered":"In\u00e8s est de retour !"},"content":{"rendered":"\n<p style=\"font-size: 18px; text-align: justify;\">Apr\u00e8s un stage dans le laboratoire l\u2019\u00e9t\u00e9 dernier, In\u00e8s est de retour de France et pr\u00eate \u00e0 commencer sa ma\u00eetrise en Biochimie ! Son projet portera sur l\u2019\u00e9pissage alternatif et la diff\u00e9renciation neuronale. Elle sera co-dirig\u00e9e avec le Pr Xavier Roucou.<\/p>\n<p>\u00a0<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"681\" height=\"1024\" src=\"https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/02\/DSC_0541-681x1024.jpg\" alt=\"\" class=\"wp-image-2772\" srcset=\"https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/02\/DSC_0541-681x1024.jpg 681w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/02\/DSC_0541-199x300.jpg 199w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/02\/DSC_0541-768x1155.jpg 768w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/02\/DSC_0541-1021x1536.jpg 1021w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/02\/DSC_0541-1362x2048.jpg 1362w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/02\/DSC_0541-scaled.jpg 1702w\" sizes=\"auto, (max-width: 681px) 100vw, 681px\" \/><figcaption>    <\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s un stage dans le laboratoire l\u2019\u00e9t\u00e9 dernier, In\u00e8s est de retour de France et pr\u00eate \u00e0 commencer sa ma\u00eetrise en Biochimie ! Son projet portera sur l\u2019\u00e9pissage alternatif et la diff\u00e9renciation neuronale. Elle sera co-dirig\u00e9e avec le Pr Xavier Roucou. \u00a0<\/p>\n","protected":false},"author":1,"featured_media":2766,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[],"class_list":["post-2771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-people-fr"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"fr","enabled_languages":["en","fr"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/posts\/2771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/comments?post=2771"}],"version-history":[{"count":2,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/posts\/2771\/revisions"}],"predecessor-version":[{"id":2774,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/posts\/2771\/revisions\/2774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/media\/2766"}],"wp:attachment":[{"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/media?parent=2771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/categories?post=2771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/tags?post=2771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}