{"id":3374,"date":"2020-07-24T15:49:00","date_gmt":"2020-07-24T19:49:00","guid":{"rendered":"https:\/\/the-laurent-lab.com\/?p=3374"},"modified":"2021-06-23T15:52:33","modified_gmt":"2021-06-23T19:52:33","slug":"pourquoi-pas","status":"publish","type":"post","link":"https:\/\/the-laurent-lab.com\/fr\/pourquoi-pas\/","title":{"rendered":"Pourquoi pas !"},"content":{"rendered":"\n<p style=\"font-size: 18px; text-align: justify;\"><span style=\"font-size: 18px;\">L\u2019\u00e9t\u00e9 est l\u00e0, les temp\u00e9ratures sont chaudes alors pourquoi ne pas aller manger une glace en milieu d\u2019apr\u00e8s-midi ? La Brasserie Fleurimont est toujours un bon choix pour un d\u00e9licieux sundae ! \ud83d\ude42<\/span><\/p>\n<p>\u00a0<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/06\/e3efdfcb-b94d-45a8-a1c0-8e4f60c0d532-1-576x1024.jpg\" alt=\"\" class=\"wp-image-3375\" srcset=\"https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/06\/e3efdfcb-b94d-45a8-a1c0-8e4f60c0d532-1-576x1024.jpg 576w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/06\/e3efdfcb-b94d-45a8-a1c0-8e4f60c0d532-1-169x300.jpg 169w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/06\/e3efdfcb-b94d-45a8-a1c0-8e4f60c0d532-1.jpg 720w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><figcaption>   <\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/06\/IMG_5627-1-scaled-e1624477910911-1024x768.jpg\" alt=\"\" class=\"wp-image-3376\" srcset=\"https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/06\/IMG_5627-1-scaled-e1624477910911-1024x768.jpg 1024w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/06\/IMG_5627-1-scaled-e1624477910911-300x225.jpg 300w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/06\/IMG_5627-1-scaled-e1624477910911-768x576.jpg 768w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/06\/IMG_5627-1-scaled-e1624477910911-1536x1152.jpg 1536w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/06\/IMG_5627-1-scaled-e1624477910911-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>   <\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9t\u00e9 est l\u00e0, les temp\u00e9ratures sont chaudes alors pourquoi ne pas aller manger une glace en milieu d\u2019apr\u00e8s-midi ? La Brasserie Fleurimont est toujours un bon choix pour un d\u00e9licieux sundae ! \ud83d\ude42 \u00a0<\/p>\n","protected":false},"author":1,"featured_media":3372,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57],"tags":[],"class_list":["post-3374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fun-fr"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"fr","enabled_languages":["en","fr"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/posts\/3374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/comments?post=3374"}],"version-history":[{"count":1,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/posts\/3374\/revisions"}],"predecessor-version":[{"id":3377,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/posts\/3374\/revisions\/3377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/media\/3372"}],"wp:attachment":[{"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/media?parent=3374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/categories?post=3374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/tags?post=3374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}