{"id":3507,"date":"2020-11-07T10:55:00","date_gmt":"2020-11-07T15:55:00","guid":{"rendered":"https:\/\/the-laurent-lab.com\/?p=3507"},"modified":"2021-07-13T10:58:10","modified_gmt":"2021-07-13T14:58:10","slug":"classes-en-plein-air","status":"publish","type":"post","link":"https:\/\/the-laurent-lab.com\/fr\/classes-en-plein-air\/","title":{"rendered":"Classes en plein air"},"content":{"rendered":"\n<p style=\"font-size: 18px; text-align: justify;\">Depuis le d\u00e9but de la pand\u00e9mie, le contexte fait que beaucoup de classes sont pass\u00e9es en mode virtuel. Cela perturbe les habitudes des \u00e9tudiants mais aussi&#8230; des professeur.e.s ! Depuis la rentr\u00e9e scolaire, une initiative a \u00e9t\u00e9 lanc\u00e9e \u00e0 l&rsquo;Universit\u00e9 de Sherbrooke : faire des classes en plein air ! Ce sont 11 classes ext\u00e9rieures qui ont \u00e9t\u00e9 mises en place et quelques 57 enseignant.e.s qui y ont eu recours. D&rsquo;apr\u00e8s un sondage r\u00e9alis\u00e9 aupr\u00e8s des \u00e9tudiants, la satisfaction est l\u00e0 ! Les \u00e9tudiants sont contents d&rsquo;avoir pu profiter de l\u2019air pur gr\u00e2ce \u00e0 ces am\u00e9nagements. Il existe peu d&rsquo;initiatives comparables ce qui suscite un grand int\u00e9r\u00eat de la part d\u2019autres universit\u00e9s au Canada. Si la pand\u00e9mie venait a durer, ces classes pourraient continuer&#8230; sauf pendant l&rsquo;hiver canadien bien sur ! \ud83d\ude42<\/p>\n<p>\u00a0<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/07\/classe-plein-air-1.jpeg\" alt=\"\" class=\"wp-image-3509\" srcset=\"https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/07\/classe-plein-air-1.jpeg 1024w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/07\/classe-plein-air-1-300x200.jpeg 300w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/07\/classe-plein-air-1-768x513.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>     <\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"366\" src=\"https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/07\/Classe-plein-air-2-1-1024x366.jpg\" alt=\"\" class=\"wp-image-3508\" srcset=\"https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/07\/Classe-plein-air-2-1-1024x366.jpg 1024w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/07\/Classe-plein-air-2-1-300x107.jpg 300w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/07\/Classe-plein-air-2-1-768x275.jpg 768w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/07\/Classe-plein-air-2-1-1536x550.jpg 1536w, https:\/\/the-laurent-lab.com\/wp-content\/uploads\/2021\/07\/Classe-plein-air-2-1-2048x733.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>   <\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Depuis le d\u00e9but de la pand\u00e9mie, le contexte fait que beaucoup de classes sont pass\u00e9es en mode virtuel. Cela perturbe les habitudes des \u00e9tudiants mais aussi&#8230; des professeur.e.s ! Depuis la rentr\u00e9e scolaire, une initiative a \u00e9t\u00e9 lanc\u00e9e \u00e0 l&rsquo;Universit\u00e9 de Sherbrooke : faire des&nbsp;<a class=\"read-more\" href=\"https:\/\/the-laurent-lab.com\/fr\/classes-en-plein-air\/\">&hellip;<\/a><\/p>\n","protected":false},"author":1,"featured_media":3504,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57],"tags":[],"class_list":["post-3507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fun-fr"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"fr","enabled_languages":["en","fr"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/posts\/3507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/comments?post=3507"}],"version-history":[{"count":2,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/posts\/3507\/revisions"}],"predecessor-version":[{"id":3511,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/posts\/3507\/revisions\/3511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/media\/3504"}],"wp:attachment":[{"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/media?parent=3507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/categories?post=3507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/the-laurent-lab.com\/fr\/wp-json\/wp\/v2\/tags?post=3507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}